{"id":182037,"date":"2025-07-25T08:00:23","date_gmt":"2025-07-25T12:00:23","guid":{"rendered":"https:\/\/zachary-jones.com\/zambombazo\/?p=182037"},"modified":"2026-01-17T05:22:52","modified_gmt":"2026-01-17T10:22:52","slug":"david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir","status":"publish","type":"post","link":"https:\/\/zachary-jones.com\/zambombazo\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\/","title":{"rendered":"David Anuar: Los &#8216;feos&#8217; del mundo maya tienen algo que decir"},"content":{"rendered":"<div class=\"video-container\">\n<div data-fullscreen=\"disabled\" data-mode=\"normal\" data-oembed=\"1\" data-provider=\"youtube\" data-reset-after-played id=\"arve-youtube-f8bhwk4m3ga\" style=\"max-width:1100px;\" class=\"arve\">\n<div class=\"arve-inner\">\n<div style=\"aspect-ratio:500\/281\" class=\"arve-embed arve-embed--has-aspect-ratio\">\n<div class=\"arve-ar\" style=\"padding-top:56.200000%\"><\/div>\n<p>\t\t\t<iframe allow=\"accelerometer &apos;none&apos;;autoplay &apos;none&apos;;bluetooth &apos;none&apos;;browsing-topics &apos;none&apos;;camera &apos;none&apos;;clipboard-read &apos;none&apos;;clipboard-write;display-capture &apos;none&apos;;encrypted-media &apos;none&apos;;gamepad &apos;none&apos;;geolocation &apos;none&apos;;gyroscope &apos;none&apos;;hid &apos;none&apos;;identity-credentials-get &apos;none&apos;;idle-detection &apos;none&apos;;keyboard-map &apos;none&apos;;local-fonts;magnetometer &apos;none&apos;;microphone &apos;none&apos;;midi &apos;none&apos;;otp-credentials &apos;none&apos;;payment &apos;none&apos;;picture-in-picture;publickey-credentials-create &apos;none&apos;;publickey-credentials-get &apos;none&apos;;screen-wake-lock &apos;none&apos;;serial &apos;none&apos;;summarizer &apos;none&apos;;sync-xhr;usb &apos;none&apos;;web-share;window-management &apos;none&apos;;xr-spatial-tracking &apos;none&apos;;\" allowfullscreen=\"\" class=\"arve-iframe fitvidsignore\" credentialless data-arve=\"arve-youtube-f8bhwk4m3ga\" data-lenis-prevent=\"\" data-src-no-ap=\"https:\/\/www.youtube-nocookie.com\/embed\/F8BHwk4M3gA?feature=oembed&#038;wmode=opaque&amp;iv_load_policy=3&amp;modestbranding=1&amp;rel=0&amp;autohide=1&amp;playsinline=0&amp;autoplay=0&amp;enablejsapi=1\" frameborder=\"0\" height=\"618.2\" loading=\"lazy\" name=\"\" referrerpolicy=\"strict-origin-when-cross-origin\" sandbox=\"allow-scripts allow-same-origin allow-presentation allow-popups allow-popups-to-escape-sandbox\" scrolling=\"no\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/F8BHwk4M3gA?feature=oembed&#038;wmode=opaque&#038;iv_load_policy=3&#038;modestbranding=1&#038;rel=0&#038;autohide=1&#038;playsinline=0&#038;autoplay=0&#038;enablejsapi=1\" title=\"David Anuar: Hablan los &quot;feos&quot;\" width=\"1100\"><\/iframe><\/p><\/div>\n<\/p><\/div>\n<p>\t<script type=\"application\/ld+json\">{\"@context\":\"http:\\\/\\\/schema.org\\\/\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\\\/#arve-youtube-f8bhwk4m3ga\",\"type\":\"VideoObject\",\"embedURL\":\"https:\\\/\\\/www.youtube-nocookie.com\\\/embed\\\/F8BHwk4M3gA?feature=oembed&wmode=opaque&iv_load_policy=3&modestbranding=1&rel=0&autohide=1&playsinline=0&autoplay=0&enablejsapi=1\",\"name\":\"David Anuar: Hablan los \\\"feos\\\"\",\"thumbnailUrl\":\"https:\\\/\\\/i.ytimg.com\\\/vi\\\/F8BHwk4M3gA\\\/hqdefault.jpg\",\"uploadDate\":\"2026-05-13T13:04:52-04:00\",\"author\":\"Zambombazo\",\"description\":\"Entrevista al poeta David Anuar durante la Feria Internacional del Libro y la Cultura (FILyC) en Playa del Carmen sobre el libro Los feos, que procura mostrar que los animales que \\\"son considerados feos, negativos o nocivos por alguna raz\\u00f3n... tienen una i\"}<\/script><\/p>\n<\/div>\n<\/div>\n<p>Entrevista al poeta David Anuar durante la Feria Internacional del Libro y la Cultura (FILyC) en Playa del Carmen sobre el libro <a href=\"https:\/\/feriadelibro.inah.gob.mx\/index.php\/35-filah\/eventos\/2239-1398los-feos\"><em>Los feos<\/em><\/a>, que procura mostrar que los animales que &#8220;son considerados feos, negativos o nocivos por alguna raz\u00f3n&#8230; tienen una importancia tanto biol\u00f3gica como cultural&#8221;. Sus poemas nos invitan a &#8220;escuchar a estos animales d\u00e1ndonos su propia versi\u00f3n de los hechos&#8221;.<\/p>\n<p>David Anuar en l\u00ednea: <a href=\"https:\/\/www.facebook.com\/archipielago.talleres\">Facebook<\/a>, <a href=\"https:\/\/www.instagram.com\/archipielago.talleres\/\">Instagram<\/a><\/p>\n<hr \/><p><em><a href=\"https:\/\/zachary-jones.com\/zambombazo\/wp-login.php?action=register\"><strong>Become a member<\/strong><\/a> of Zambombazo today to gain access to this member-exclusive teaching activity plus thousands of other Spanish classroom activities on a wide variety of topics!<\/p><p>Already a member? <a href=\"https:\/\/zachary-jones.com\/zambombazo\/login\/\"><strong>Log in<\/strong><\/a> to access this activity.<\/em><\/p><hr \/>\n\n<h5>Transcripci\u00f3n<\/h5>\n<p>El libro que estoy presentando, o que he presentado en esta Feria del Libro, es un libro de una postura muy bella, donde justo, pues, hablamos de animales de la pen\u00ednsula de Yucat\u00e1n que dentro del imaginario maya son considerados feos, negativos o nocivos por alguna raz\u00f3n y justo en este libro lo que procuramos es mostrar su importancia biol\u00f3gica y tambi\u00e9n cultural. Tienen una importancia tanto biol\u00f3gica como cultural. Mi colaboraci\u00f3n dentro de este libro fue la escritura de los poemas. <\/p>\n<p>Usualmente cuando pensamos en el mundo, lo pensamos desde nuestra humanidad, desde nuestro cerebro humano y hay que reconocer que tenemos una visi\u00f3n antrococentrista, es decir, todo lo medimos con la regla humana, cuando hay que reconocer que tambi\u00e9n hay otros seres que habitan este mundo y que merecen igual respeto que nosotros los humanos.<\/p>\n<p>[pullquote-right]\ud83e\udda8 \u00bfQu\u00e9 dir\u00eda un zorrillo de s\u00ed mismo?[\/pullquote-right] Entonces cuando yo le\u00eda el libro yo me hac\u00eda una pregunta constantemente. Eran los cient\u00edficos hablando de los animales, los bi\u00f3logos, los antrop\u00f3logos y me dec\u00eda: Est\u00e1 muy bien lo que est\u00e1n escribiendo, pero yo me preguntaba: \u00bfQu\u00e9 tendr\u00e1n que decirnos estos animales? \u00bfQu\u00e9 dir\u00eda un zorrillo de s\u00ed mismo? \u00bfQu\u00e9 dir\u00eda un rat\u00f3n de s\u00ed mismo?<\/p>\n<p>Entonces, a partir de ello dije: Bueno, no voy a escribir los poemas en tercera persona. Porque es usualmente lo que se hace, poemas paisajistas, donde yo voy a ponerme a describir al rat\u00f3n y sus atributos y le voy a hacer una oda al ratoncito que est\u00e1 muy bonito. Entonces, yo dec\u00eda: Creo que no es ese el camino.<\/p>\n<p>Y entonces lo que hice fue usar una t\u00e9cnica literaria que se llama mon\u00f3logo dram\u00e1tico, donde justo t\u00fa le das la voz a un personaje. Para m\u00ed, estos personajes eran los feos, estos animales. Por eso yo titulaba un poco a mi idea: Hablan los feos. Pues, un poco era la idea de escuchar a estos animales d\u00e1ndonos su propia versi\u00f3n de los hechos. <\/p>\n<h5>Unidades did\u00e1cticas relacionadas<\/h5>\n<ul>\n<li><a href=\"https:\/\/zachary-jones.com\/zambombazo\/animals-pets\/\">Los animales<\/a><\/li>\n<li><a href=\"https:\/\/zachary-jones.com\/zambombazo\/environment-nature\/\">El medio ambiente y la naturaleza<\/a><\/li>\n<li><a href=\"https:\/\/zachary-jones.com\/zambombazo\/self-esteem-standards-of-beauty\/\">La autoestima y los c\u00e1nones de belleza<\/a><\/li>\n<li><a href=\"https:\/\/zachary-jones.com\/zambombazo\/poetry\/\">La poes\u00eda<\/a><\/li>\n<li><a href=\"https:\/\/zachary-jones.com\/zambombazo\/humanidades-3-naturaleza-humanidad\/\">Humanidades 3: Naturaleza \/ Humanidad<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Entrevista al poeta David Anuar sobre el libro <em>Los feos<\/em>: &#8220;\u00bfQu\u00e9 tendr\u00e1n que decirnos estos animales? \u00bfQu\u00e9 dir\u00eda un zorrillo de s\u00ed mismo?&#8221;.<\/p>\n","protected":false},"author":3,"featured_media":182090,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","footnotes":""},"categories":[123],"tags":[516,548,939,272,937,491,45,233,715],"class_list":["post-182037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-literatura","tag-animales","tag-autoestima","tag-el-jugo","tag-entrevista","tag-maya","tag-medio-ambiente","tag-mexico","tag-poesia","tag-preguntitas","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>David Anuar: Los &#039;feos&#039; del mundo maya tienen algo que decir<\/title>\n<meta name=\"description\" content=\"Entrevista al poeta David Anuar sobre el libro Los feos: &quot;\u00bfQu\u00e9 tendr\u00e1n que decirnos estos animales? \u00bfQu\u00e9 dir\u00eda un zorrillo de s\u00ed mismo?&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zachary-jones.com\/zambombazo\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"David Anuar: Los &#039;feos&#039; del mundo maya tienen algo que decir\" \/>\n<meta property=\"og:description\" content=\"Entrevista al poeta David Anuar sobre el libro Los feos: &quot;\u00bfQu\u00e9 tendr\u00e1n que decirnos estos animales? \u00bfQu\u00e9 dir\u00eda un zorrillo de s\u00ed mismo?&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zachary-jones.com\/zambombazo\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\/\" \/>\n<meta property=\"og:site_name\" content=\"Zambombazo\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-25T12:00:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-17T10:22:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zachary-jones.com\/zambombazo\/wp-content\/uploads\/2025\/04\/david_anuar_hablan_los_feos-f.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Zachary &amp; Betsy Jones\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Zamb0mbazo\" \/>\n<meta name=\"twitter:site\" content=\"@Zamb0mbazo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Zachary &amp; Betsy Jones\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\\\/\"},\"author\":{\"name\":\"Zachary &amp; Betsy Jones\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#\\\/schema\\\/person\\\/9102799d8a516e01862183d162194000\"},\"headline\":\"David Anuar: Los &#8216;feos&#8217; del mundo maya tienen algo que decir\",\"datePublished\":\"2025-07-25T12:00:23+00:00\",\"dateModified\":\"2026-01-17T10:22:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\\\/\"},\"wordCount\":492,\"publisher\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/david_anuar_hablan_los_feos-f.jpg\",\"keywords\":[\"Animales\",\"Autoestima\",\"El Jugo\",\"Entrevista\",\"Maya\",\"Medio ambiente\",\"M\u00e9xico\",\"Poes\u00eda\",\"Preguntitas\"],\"articleSection\":[\"Literatura\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\\\/\",\"url\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\\\/\",\"name\":\"David Anuar: Los 'feos' del mundo maya tienen algo que decir\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/david_anuar_hablan_los_feos-f.jpg\",\"datePublished\":\"2025-07-25T12:00:23+00:00\",\"dateModified\":\"2026-01-17T10:22:52+00:00\",\"description\":\"Entrevista al poeta David Anuar sobre el libro Los feos: \\\"\u00bfQu\u00e9 tendr\u00e1n que decirnos estos animales? \u00bfQu\u00e9 dir\u00eda un zorrillo de s\u00ed mismo?\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/david_anuar_hablan_los_feos-f.jpg\",\"contentUrl\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/david_anuar_hablan_los_feos-f.jpg\",\"width\":720,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"David Anuar: Los &#8216;feos&#8217; del mundo maya tienen algo que decir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#website\",\"url\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/\",\"name\":\"Zambombazo\",\"description\":\"Lengua, m\u00fasica y cultura\",\"publisher\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#organization\",\"name\":\"Zambombazo\",\"url\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/zambombazo_logo_google_knowledge_graph.png\",\"contentUrl\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/zambombazo_logo_google_knowledge_graph.png\",\"width\":1000,\"height\":134,\"caption\":\"Zambombazo\"},\"image\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Zamb0mbazo\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/profzjones\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#\\\/schema\\\/person\\\/9102799d8a516e01862183d162194000\",\"name\":\"Zachary &amp; Betsy Jones\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a375434a90c98816c5c553aac3b90f9579cfde7e18a43601be11509e2ec973dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a375434a90c98816c5c553aac3b90f9579cfde7e18a43601be11509e2ec973dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a375434a90c98816c5c553aac3b90f9579cfde7e18a43601be11509e2ec973dd?s=96&d=mm&r=g\",\"caption\":\"Zachary &amp; Betsy Jones\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"David Anuar: Los 'feos' del mundo maya tienen algo que decir","description":"Entrevista al poeta David Anuar sobre el libro Los feos: \"\u00bfQu\u00e9 tendr\u00e1n que decirnos estos animales? \u00bfQu\u00e9 dir\u00eda un zorrillo de s\u00ed mismo?\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zachary-jones.com\/zambombazo\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\/","og_locale":"en_US","og_type":"article","og_title":"David Anuar: Los 'feos' del mundo maya tienen algo que decir","og_description":"Entrevista al poeta David Anuar sobre el libro Los feos: \"\u00bfQu\u00e9 tendr\u00e1n que decirnos estos animales? \u00bfQu\u00e9 dir\u00eda un zorrillo de s\u00ed mismo?\".","og_url":"https:\/\/zachary-jones.com\/zambombazo\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\/","og_site_name":"Zambombazo","article_published_time":"2025-07-25T12:00:23+00:00","article_modified_time":"2026-01-17T10:22:52+00:00","og_image":[{"width":720,"height":340,"url":"https:\/\/zachary-jones.com\/zambombazo\/wp-content\/uploads\/2025\/04\/david_anuar_hablan_los_feos-f.jpg","type":"image\/jpeg"}],"author":"Zachary &amp; Betsy Jones","twitter_card":"summary_large_image","twitter_creator":"@Zamb0mbazo","twitter_site":"@Zamb0mbazo","twitter_misc":{"Written by":"Zachary &amp; Betsy Jones","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zachary-jones.com\/zambombazo\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\/#article","isPartOf":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\/"},"author":{"name":"Zachary &amp; Betsy Jones","@id":"https:\/\/zachary-jones.com\/zambombazo\/#\/schema\/person\/9102799d8a516e01862183d162194000"},"headline":"David Anuar: Los &#8216;feos&#8217; del mundo maya tienen algo que decir","datePublished":"2025-07-25T12:00:23+00:00","dateModified":"2026-01-17T10:22:52+00:00","mainEntityOfPage":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\/"},"wordCount":492,"publisher":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/#organization"},"image":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\/#primaryimage"},"thumbnailUrl":"https:\/\/zachary-jones.com\/zambombazo\/wp-content\/uploads\/2025\/04\/david_anuar_hablan_los_feos-f.jpg","keywords":["Animales","Autoestima","El Jugo","Entrevista","Maya","Medio ambiente","M\u00e9xico","Poes\u00eda","Preguntitas"],"articleSection":["Literatura"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/zachary-jones.com\/zambombazo\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\/","url":"https:\/\/zachary-jones.com\/zambombazo\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\/","name":"David Anuar: Los 'feos' del mundo maya tienen algo que decir","isPartOf":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\/#primaryimage"},"image":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\/#primaryimage"},"thumbnailUrl":"https:\/\/zachary-jones.com\/zambombazo\/wp-content\/uploads\/2025\/04\/david_anuar_hablan_los_feos-f.jpg","datePublished":"2025-07-25T12:00:23+00:00","dateModified":"2026-01-17T10:22:52+00:00","description":"Entrevista al poeta David Anuar sobre el libro Los feos: \"\u00bfQu\u00e9 tendr\u00e1n que decirnos estos animales? \u00bfQu\u00e9 dir\u00eda un zorrillo de s\u00ed mismo?\".","breadcrumb":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zachary-jones.com\/zambombazo\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zachary-jones.com\/zambombazo\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\/#primaryimage","url":"https:\/\/zachary-jones.com\/zambombazo\/wp-content\/uploads\/2025\/04\/david_anuar_hablan_los_feos-f.jpg","contentUrl":"https:\/\/zachary-jones.com\/zambombazo\/wp-content\/uploads\/2025\/04\/david_anuar_hablan_los_feos-f.jpg","width":720,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/zachary-jones.com\/zambombazo\/david-anuar-los-feos-del-mundo-maya-tienen-algo-que-decir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zachary-jones.com\/zambombazo\/"},{"@type":"ListItem","position":2,"name":"David Anuar: Los &#8216;feos&#8217; del mundo maya tienen algo que decir"}]},{"@type":"WebSite","@id":"https:\/\/zachary-jones.com\/zambombazo\/#website","url":"https:\/\/zachary-jones.com\/zambombazo\/","name":"Zambombazo","description":"Lengua, m\u00fasica y cultura","publisher":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zachary-jones.com\/zambombazo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zachary-jones.com\/zambombazo\/#organization","name":"Zambombazo","url":"https:\/\/zachary-jones.com\/zambombazo\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zachary-jones.com\/zambombazo\/#\/schema\/logo\/image\/","url":"https:\/\/zachary-jones.com\/zambombazo\/wp-content\/uploads\/2014\/05\/zambombazo_logo_google_knowledge_graph.png","contentUrl":"https:\/\/zachary-jones.com\/zambombazo\/wp-content\/uploads\/2014\/05\/zambombazo_logo_google_knowledge_graph.png","width":1000,"height":134,"caption":"Zambombazo"},"image":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Zamb0mbazo","https:\/\/www.youtube.com\/user\/profzjones"]},{"@type":"Person","@id":"https:\/\/zachary-jones.com\/zambombazo\/#\/schema\/person\/9102799d8a516e01862183d162194000","name":"Zachary &amp; Betsy Jones","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a375434a90c98816c5c553aac3b90f9579cfde7e18a43601be11509e2ec973dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a375434a90c98816c5c553aac3b90f9579cfde7e18a43601be11509e2ec973dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a375434a90c98816c5c553aac3b90f9579cfde7e18a43601be11509e2ec973dd?s=96&d=mm&r=g","caption":"Zachary &amp; Betsy Jones"}}]}},"_links":{"self":[{"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/posts\/182037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/comments?post=182037"}],"version-history":[{"count":5,"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/posts\/182037\/revisions"}],"predecessor-version":[{"id":190206,"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/posts\/182037\/revisions\/190206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/media\/182090"}],"wp:attachment":[{"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/media?parent=182037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/categories?post=182037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/tags?post=182037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}