{"id":157590,"date":"2021-10-26T08:00:47","date_gmt":"2021-10-26T12:00:47","guid":{"rendered":"https:\/\/zachary-jones.com\/zambombazo\/?p=157590"},"modified":"2021-09-20T15:58:17","modified_gmt":"2021-09-20T19:58:17","slug":"cancionero-bomba-estereo-yemi-alade-conexion-total","status":"publish","type":"post","link":"https:\/\/zachary-jones.com\/zambombazo\/cancionero-bomba-estereo-yemi-alade-conexion-total\/","title":{"rendered":"Cancionero: Bomba Est\u00e9reo, Yemi Alade &#8211; Conexi\u00f3n total"},"content":{"rendered":"<div class=\"video-container\">\n<div data-fullscreen=\"disabled\" data-mode=\"normal\" data-oembed=\"1\" data-provider=\"youtube\" data-reset-after-played id=\"arve-youtube-aspnpsgkdig\" style=\"max-width:1100px;\" class=\"arve\">\n<div class=\"arve-inner\">\n<div style=\"aspect-ratio:500\/281\" class=\"arve-embed arve-embed--has-aspect-ratio\">\n<div class=\"arve-ar\" style=\"padding-top:56.200000%\"><\/div>\n<p>\t\t\t<iframe allow=\"accelerometer &apos;none&apos;;autoplay &apos;none&apos;;bluetooth &apos;none&apos;;browsing-topics &apos;none&apos;;camera &apos;none&apos;;clipboard-read &apos;none&apos;;clipboard-write;display-capture &apos;none&apos;;encrypted-media &apos;none&apos;;gamepad &apos;none&apos;;geolocation &apos;none&apos;;gyroscope &apos;none&apos;;hid &apos;none&apos;;identity-credentials-get &apos;none&apos;;idle-detection &apos;none&apos;;keyboard-map &apos;none&apos;;local-fonts;magnetometer &apos;none&apos;;microphone &apos;none&apos;;midi &apos;none&apos;;otp-credentials &apos;none&apos;;payment &apos;none&apos;;picture-in-picture;publickey-credentials-create &apos;none&apos;;publickey-credentials-get &apos;none&apos;;screen-wake-lock &apos;none&apos;;serial &apos;none&apos;;summarizer &apos;none&apos;;sync-xhr;usb &apos;none&apos;;web-share;window-management &apos;none&apos;;xr-spatial-tracking &apos;none&apos;;\" allowfullscreen=\"\" class=\"arve-iframe fitvidsignore\" credentialless data-arve=\"arve-youtube-aspnpsgkdig\" data-lenis-prevent=\"\" data-src-no-ap=\"https:\/\/www.youtube-nocookie.com\/embed\/aSpnPSGkDIg?feature=oembed&#038;wmode=opaque&amp;iv_load_policy=3&amp;modestbranding=1&amp;rel=0&amp;autohide=1&amp;playsinline=0&amp;autoplay=0&amp;enablejsapi=1\" frameborder=\"0\" height=\"618.2\" loading=\"lazy\" name=\"\" referrerpolicy=\"strict-origin-when-cross-origin\" sandbox=\"allow-scripts allow-same-origin allow-presentation allow-popups allow-popups-to-escape-sandbox\" scrolling=\"no\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/aSpnPSGkDIg?feature=oembed&#038;wmode=opaque&#038;iv_load_policy=3&#038;modestbranding=1&#038;rel=0&#038;autohide=1&#038;playsinline=0&#038;autoplay=0&#038;enablejsapi=1\" title=\"Bomba Est\u00e9reo, Yemi Alade - Conexi\u00f3n Total (Audio)\" width=\"1100\"><\/iframe><\/p><\/div>\n<\/p><\/div>\n<p>\t<script type=\"application\/ld+json\">{\"@context\":\"http:\\\/\\\/schema.org\\\/\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/cancionero-bomba-estereo-yemi-alade-conexion-total\\\/#arve-youtube-aspnpsgkdig\",\"type\":\"VideoObject\",\"embedURL\":\"https:\\\/\\\/www.youtube-nocookie.com\\\/embed\\\/aSpnPSGkDIg?feature=oembed&wmode=opaque&iv_load_policy=3&modestbranding=1&rel=0&autohide=1&playsinline=0&autoplay=0&enablejsapi=1\",\"name\":\"Bomba Est\\u00e9reo, Yemi Alade - Conexi\\u00f3n Total (Audio)\",\"thumbnailUrl\":\"https:\\\/\\\/i.ytimg.com\\\/vi\\\/aSpnPSGkDIg\\\/hqdefault.jpg\",\"uploadDate\":\"2026-05-13T18:08:16-04:00\",\"author\":\"BombaEstereoVEVO\",\"description\":\"\\\"Conexi\\u00f3n total\\\" de Bomba Est\\u00e9reo con Yemi Alade dice: \\\"Yo lo que quiero es tenerte aqu\\u00ed, ahorita contigo sin tanto escribir. No mires mis fotos y m\\u00edrame a m\\u00ed\\\". Despu\\u00e9s de bailar, vamos a reflexionar sobre la conjugaci\\u00f3n de cuerpo, tiempo y espacio en el b\"}<\/script><\/p>\n<\/div>\n<\/div>\n<p>&#8220;Conexi\u00f3n total&#8221; de Bomba Est\u00e9reo con Yemi Alade dice: &#8220;Yo lo que quiero es tenerte aqu\u00ed, ahorita contigo sin tanto escribir. No mires mis fotos y m\u00edrame a m\u00ed&#8221;.<\/p>\n<p>Despu\u00e9s de bailar, vamos a reflexionar sobre la conjugaci\u00f3n de cuerpo, tiempo y espacio en el baile y tambi\u00e9n en la educaci\u00f3n virtual y presencial.<\/p>\n<p>Pa\u00eds: Colombia, Nigeria<\/p>\n<p>G\u00e9nero: Electr\u00f3nica<\/p>\n<p>Temas: La virtualidad y la presencialidad<\/p>\n<hr \/><p><em><a href=\"https:\/\/zachary-jones.com\/zambombazo\/wp-login.php?action=register\"><strong>Become a member<\/strong><\/a> of Zambombazo today to gain access to this member-exclusive teaching activity plus thousands of other Spanish classroom activities on a wide variety of topics!<\/p><p>Already a member? <a href=\"https:\/\/zachary-jones.com\/zambombazo\/login\/\"><strong>Log in<\/strong><\/a> to access this activity.<\/em><\/p><hr \/>\n\n<h5>Unidades did\u00e1cticas relacionadas<\/h5>\n<ul>\n<li><a href=\"https:\/\/zachary-jones.com\/zambombazo\/media-technology\/\">Los medios de comunicaci\u00f3n y la tecnolog\u00eda<\/a><\/li>\n<li><a href=\"https:\/\/zachary-jones.com\/zambombazo\/social-media\/\">Las redes sociales<\/a><\/li>\n<li><a href=\"https:\/\/zachary-jones.com\/zambombazo\/dance\/\">El baile<\/a><\/li>\n<li><a href=\"https:\/\/zachary-jones.com\/zambombazo\/social-and-emotional-learning-during-the-pandemic\/\">El aprendizaje social y emocional durante la pandemia<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Conexi\u00f3n total&#8221; de Bomba Est\u00e9reo con Yemi Alade: &#8220;Lo que quiero es tenerte aqu\u00ed, ahorita contigo sin tanto escribir. No mires mis fotos y m\u00edrame a m\u00ed&#8221;.<\/p>\n","protected":false},"author":3,"featured_media":157611,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","footnotes":""},"categories":[4],"tags":[519,464,163,17,168,725,566,546],"class_list":["post-157590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-afrodescendiente","tag-baile","tag-cancionero","tag-colombia","tag-electronica","tag-nigeria","tag-redes-sociales","tag-tecnologia","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cancionero: Bomba Est\u00e9reo, Yemi Alade - Conexi\u00f3n total<\/title>\n<meta name=\"description\" content=\"&quot;Conexi\u00f3n total&quot; de Bomba Est\u00e9reo con Yemi Alade: &quot;Lo que quiero es tenerte aqu\u00ed, ahorita contigo sin tanto escribir. No mires mis fotos y m\u00edrame a m\u00ed&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zachary-jones.com\/zambombazo\/cancionero-bomba-estereo-yemi-alade-conexion-total\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cancionero: Bomba Est\u00e9reo, Yemi Alade - Conexi\u00f3n total\" \/>\n<meta property=\"og:description\" content=\"&quot;Conexi\u00f3n total&quot; de Bomba Est\u00e9reo con Yemi Alade: &quot;Lo que quiero es tenerte aqu\u00ed, ahorita contigo sin tanto escribir. No mires mis fotos y m\u00edrame a m\u00ed&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zachary-jones.com\/zambombazo\/cancionero-bomba-estereo-yemi-alade-conexion-total\/\" \/>\n<meta property=\"og:site_name\" content=\"Zambombazo\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-26T12:00:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zachary-jones.com\/zambombazo\/wp-content\/uploads\/2021\/09\/bomba_estereo_yemi_alade_-_conexion_total-f.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Zachary &amp; Betsy Jones\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Zamb0mbazo\" \/>\n<meta name=\"twitter:site\" content=\"@Zamb0mbazo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Zachary &amp; Betsy Jones\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/cancionero-bomba-estereo-yemi-alade-conexion-total\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/cancionero-bomba-estereo-yemi-alade-conexion-total\\\/\"},\"author\":{\"name\":\"Zachary &amp; Betsy Jones\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#\\\/schema\\\/person\\\/9102799d8a516e01862183d162194000\"},\"headline\":\"Cancionero: Bomba Est\u00e9reo, Yemi Alade &#8211; Conexi\u00f3n total\",\"datePublished\":\"2021-10-26T12:00:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/cancionero-bomba-estereo-yemi-alade-conexion-total\\\/\"},\"wordCount\":132,\"publisher\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/cancionero-bomba-estereo-yemi-alade-conexion-total\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/bomba_estereo_yemi_alade_-_conexion_total-f.jpg\",\"keywords\":[\"Afrodescendiente\",\"Baile\",\"Cancionero\",\"Colombia\",\"Electr\u00f3nica\",\"Nigeria\",\"Redes sociales\",\"Tecnolog\u00eda\"],\"articleSection\":[\"M\u00fasica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/cancionero-bomba-estereo-yemi-alade-conexion-total\\\/\",\"url\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/cancionero-bomba-estereo-yemi-alade-conexion-total\\\/\",\"name\":\"Cancionero: Bomba Est\u00e9reo, Yemi Alade - Conexi\u00f3n total\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/cancionero-bomba-estereo-yemi-alade-conexion-total\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/cancionero-bomba-estereo-yemi-alade-conexion-total\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/bomba_estereo_yemi_alade_-_conexion_total-f.jpg\",\"datePublished\":\"2021-10-26T12:00:47+00:00\",\"description\":\"\\\"Conexi\u00f3n total\\\" de Bomba Est\u00e9reo con Yemi Alade: \\\"Lo que quiero es tenerte aqu\u00ed, ahorita contigo sin tanto escribir. No mires mis fotos y m\u00edrame a m\u00ed\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/cancionero-bomba-estereo-yemi-alade-conexion-total\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/cancionero-bomba-estereo-yemi-alade-conexion-total\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/cancionero-bomba-estereo-yemi-alade-conexion-total\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/bomba_estereo_yemi_alade_-_conexion_total-f.jpg\",\"contentUrl\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/bomba_estereo_yemi_alade_-_conexion_total-f.jpg\",\"width\":720,\"height\":340,\"caption\":\"Bomba Est\u00e9reo, Yemi Alade - Conexi\u00f3n total\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/cancionero-bomba-estereo-yemi-alade-conexion-total\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cancionero: Bomba Est\u00e9reo, Yemi Alade &#8211; Conexi\u00f3n total\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#website\",\"url\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/\",\"name\":\"Zambombazo\",\"description\":\"Lengua, m\u00fasica y cultura\",\"publisher\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#organization\",\"name\":\"Zambombazo\",\"url\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/zambombazo_logo_google_knowledge_graph.png\",\"contentUrl\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/zambombazo_logo_google_knowledge_graph.png\",\"width\":1000,\"height\":134,\"caption\":\"Zambombazo\"},\"image\":{\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Zamb0mbazo\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/profzjones\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zachary-jones.com\\\/zambombazo\\\/#\\\/schema\\\/person\\\/9102799d8a516e01862183d162194000\",\"name\":\"Zachary &amp; Betsy Jones\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a375434a90c98816c5c553aac3b90f9579cfde7e18a43601be11509e2ec973dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a375434a90c98816c5c553aac3b90f9579cfde7e18a43601be11509e2ec973dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a375434a90c98816c5c553aac3b90f9579cfde7e18a43601be11509e2ec973dd?s=96&d=mm&r=g\",\"caption\":\"Zachary &amp; Betsy Jones\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cancionero: Bomba Est\u00e9reo, Yemi Alade - Conexi\u00f3n total","description":"\"Conexi\u00f3n total\" de Bomba Est\u00e9reo con Yemi Alade: \"Lo que quiero es tenerte aqu\u00ed, ahorita contigo sin tanto escribir. No mires mis fotos y m\u00edrame a m\u00ed\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zachary-jones.com\/zambombazo\/cancionero-bomba-estereo-yemi-alade-conexion-total\/","og_locale":"en_US","og_type":"article","og_title":"Cancionero: Bomba Est\u00e9reo, Yemi Alade - Conexi\u00f3n total","og_description":"\"Conexi\u00f3n total\" de Bomba Est\u00e9reo con Yemi Alade: \"Lo que quiero es tenerte aqu\u00ed, ahorita contigo sin tanto escribir. No mires mis fotos y m\u00edrame a m\u00ed\".","og_url":"https:\/\/zachary-jones.com\/zambombazo\/cancionero-bomba-estereo-yemi-alade-conexion-total\/","og_site_name":"Zambombazo","article_published_time":"2021-10-26T12:00:47+00:00","og_image":[{"width":720,"height":340,"url":"https:\/\/zachary-jones.com\/zambombazo\/wp-content\/uploads\/2021\/09\/bomba_estereo_yemi_alade_-_conexion_total-f.jpg","type":"image\/jpeg"}],"author":"Zachary &amp; Betsy Jones","twitter_card":"summary_large_image","twitter_creator":"@Zamb0mbazo","twitter_site":"@Zamb0mbazo","twitter_misc":{"Written by":"Zachary &amp; Betsy Jones","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zachary-jones.com\/zambombazo\/cancionero-bomba-estereo-yemi-alade-conexion-total\/#article","isPartOf":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/cancionero-bomba-estereo-yemi-alade-conexion-total\/"},"author":{"name":"Zachary &amp; Betsy Jones","@id":"https:\/\/zachary-jones.com\/zambombazo\/#\/schema\/person\/9102799d8a516e01862183d162194000"},"headline":"Cancionero: Bomba Est\u00e9reo, Yemi Alade &#8211; Conexi\u00f3n total","datePublished":"2021-10-26T12:00:47+00:00","mainEntityOfPage":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/cancionero-bomba-estereo-yemi-alade-conexion-total\/"},"wordCount":132,"publisher":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/#organization"},"image":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/cancionero-bomba-estereo-yemi-alade-conexion-total\/#primaryimage"},"thumbnailUrl":"https:\/\/zachary-jones.com\/zambombazo\/wp-content\/uploads\/2021\/09\/bomba_estereo_yemi_alade_-_conexion_total-f.jpg","keywords":["Afrodescendiente","Baile","Cancionero","Colombia","Electr\u00f3nica","Nigeria","Redes sociales","Tecnolog\u00eda"],"articleSection":["M\u00fasica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/zachary-jones.com\/zambombazo\/cancionero-bomba-estereo-yemi-alade-conexion-total\/","url":"https:\/\/zachary-jones.com\/zambombazo\/cancionero-bomba-estereo-yemi-alade-conexion-total\/","name":"Cancionero: Bomba Est\u00e9reo, Yemi Alade - Conexi\u00f3n total","isPartOf":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/cancionero-bomba-estereo-yemi-alade-conexion-total\/#primaryimage"},"image":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/cancionero-bomba-estereo-yemi-alade-conexion-total\/#primaryimage"},"thumbnailUrl":"https:\/\/zachary-jones.com\/zambombazo\/wp-content\/uploads\/2021\/09\/bomba_estereo_yemi_alade_-_conexion_total-f.jpg","datePublished":"2021-10-26T12:00:47+00:00","description":"\"Conexi\u00f3n total\" de Bomba Est\u00e9reo con Yemi Alade: \"Lo que quiero es tenerte aqu\u00ed, ahorita contigo sin tanto escribir. No mires mis fotos y m\u00edrame a m\u00ed\".","breadcrumb":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/cancionero-bomba-estereo-yemi-alade-conexion-total\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zachary-jones.com\/zambombazo\/cancionero-bomba-estereo-yemi-alade-conexion-total\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zachary-jones.com\/zambombazo\/cancionero-bomba-estereo-yemi-alade-conexion-total\/#primaryimage","url":"https:\/\/zachary-jones.com\/zambombazo\/wp-content\/uploads\/2021\/09\/bomba_estereo_yemi_alade_-_conexion_total-f.jpg","contentUrl":"https:\/\/zachary-jones.com\/zambombazo\/wp-content\/uploads\/2021\/09\/bomba_estereo_yemi_alade_-_conexion_total-f.jpg","width":720,"height":340,"caption":"Bomba Est\u00e9reo, Yemi Alade - Conexi\u00f3n total"},{"@type":"BreadcrumbList","@id":"https:\/\/zachary-jones.com\/zambombazo\/cancionero-bomba-estereo-yemi-alade-conexion-total\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zachary-jones.com\/zambombazo\/"},{"@type":"ListItem","position":2,"name":"Cancionero: Bomba Est\u00e9reo, Yemi Alade &#8211; Conexi\u00f3n total"}]},{"@type":"WebSite","@id":"https:\/\/zachary-jones.com\/zambombazo\/#website","url":"https:\/\/zachary-jones.com\/zambombazo\/","name":"Zambombazo","description":"Lengua, m\u00fasica y cultura","publisher":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zachary-jones.com\/zambombazo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zachary-jones.com\/zambombazo\/#organization","name":"Zambombazo","url":"https:\/\/zachary-jones.com\/zambombazo\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zachary-jones.com\/zambombazo\/#\/schema\/logo\/image\/","url":"https:\/\/zachary-jones.com\/zambombazo\/wp-content\/uploads\/2014\/05\/zambombazo_logo_google_knowledge_graph.png","contentUrl":"https:\/\/zachary-jones.com\/zambombazo\/wp-content\/uploads\/2014\/05\/zambombazo_logo_google_knowledge_graph.png","width":1000,"height":134,"caption":"Zambombazo"},"image":{"@id":"https:\/\/zachary-jones.com\/zambombazo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Zamb0mbazo","https:\/\/www.youtube.com\/user\/profzjones"]},{"@type":"Person","@id":"https:\/\/zachary-jones.com\/zambombazo\/#\/schema\/person\/9102799d8a516e01862183d162194000","name":"Zachary &amp; Betsy Jones","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a375434a90c98816c5c553aac3b90f9579cfde7e18a43601be11509e2ec973dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a375434a90c98816c5c553aac3b90f9579cfde7e18a43601be11509e2ec973dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a375434a90c98816c5c553aac3b90f9579cfde7e18a43601be11509e2ec973dd?s=96&d=mm&r=g","caption":"Zachary &amp; Betsy Jones"}}]}},"_links":{"self":[{"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/posts\/157590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/comments?post=157590"}],"version-history":[{"count":0,"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/posts\/157590\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/media\/157611"}],"wp:attachment":[{"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/media?parent=157590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/categories?post=157590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zachary-jones.com\/zambombazo\/wp-json\/wp\/v2\/tags?post=157590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}